{"id":676,"date":"2017-09-25T21:30:54","date_gmt":"2017-09-25T20:30:54","guid":{"rendered":"http:\/\/mariajosesotos.es\/?p=676"},"modified":"2017-09-25T21:30:54","modified_gmt":"2017-09-25T20:30:54","slug":"140917-procesion-en-honor-virgen-de-los-dolores-y-cristo-de-la-consolacion","status":"publish","type":"post","link":"http:\/\/mariajosesotos.es\/index.php\/2017\/09\/25\/140917-procesion-en-honor-virgen-de-los-dolores-y-cristo-de-la-consolacion\/","title":{"rendered":"140917 procesi\u00f3n en honor virgen de los dolores y cristo de la consolaci\u00f3n"},"content":{"rendered":"\t\t\t\n\t\t\t<!-- Blueimp gallery -->\n\t\t\t<div id=\"blueimp-gallery\" class=\"blueimp-gallery blueimp-gallery-controls\">\n\t\t\t\t<div class=\"slides\"><\/div>\n\t\t\t\t<h3 class=\"title\"><\/h3>\n\t\t\t\t<a class=\"prev\">\u2039<\/a>\n\t\t\t\t<a class=\"next\">\u203a<\/a>\n\t\t\t\t<a class=\"close\">\u00d7<\/a>\n\t\t\t\t<a class=\"play-pause\"><\/a>\n\t\t\t\t<ol class=\"indicator\"><\/ol>\n\t\t\t\t<div class=\"modal fade\">\n\t\t\t\t\t<div class=\"modal-dialog\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" aria-hidden=\"true\">&times;<\/button>\n\t\t\t\t\t\t\t\t<h4 class=\"modal-title\"><\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body next\"><\/div>\n\t\t\t\t\t\t\t<div class=\"modal-footer\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn btn-default pull-left prev\">\n\t\t\t\t\t\t\t\t\t<i class=\"glyphicon glyphicon-chevron-left\"><\/i>\n\t\t\t\t\t\t\t\t\tPrevious\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn btn-primary next\">\n\t\t\t\t\t\t\t\t\tNext\t\t\t\t\t\t\t\t\t<i class=\"glyphicon glyphicon-chevron-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<script type=\"text\/javascript\">\n\t\t\tjQuery(function() {\n\t\t\t\t\/\/ Set blueimp gallery options\n\t\t\t\tjQuery.extend(blueimp.Gallery.prototype.options, {\n\t\t\t\t\tuseBootstrapModal: false,\n\t\t\t\t\thidePageScrollbars: false\n\t\t\t\t});\n\t\t\t});\n\t\t\t<\/script>\n\t\t\t\n<p>Procesi\u00f3n en la cu\u00e1l gente del pueblo`pasean por algunas de las calles del pueblo con los santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Procesi\u00f3n en la cu\u00e1l gente del pueblo`pasean por algunas de las calles del pueblo con los santos<\/p>\n","protected":false},"author":2,"featured_media":677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[7,3],"tags":[151,150,149,68,26,124,148],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"http:\/\/mariajosesotos.es\/wp-content\/uploads\/2017\/09\/36496228464_7a2ba4052d_k.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p89WIH-aU","_links":{"self":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/676"}],"collection":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":1,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/676\/revisions"}],"predecessor-version":[{"id":678,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/676\/revisions\/678"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/media\/677"}],"wp:attachment":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/media?parent=676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/categories?post=676"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/tags?post=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}