{"id":1037,"date":"2018-07-11T22:01:09","date_gmt":"2018-07-11T21:01:09","guid":{"rendered":"http:\/\/mariajosesotos.es\/?p=1037"},"modified":"2018-07-11T22:01:09","modified_gmt":"2018-07-11T21:01:09","slug":"220618-vii-arte-efimero-elche","status":"publish","type":"post","link":"http:\/\/mariajosesotos.es\/index.php\/2018\/07\/11\/220618-vii-arte-efimero-elche\/","title":{"rendered":"220618 VII Arte Ef\u00edmero elche"},"content":{"rendered":"\t\t\t\n\t\t\t<!-- Blueimp gallery -->\n\t\t\t<div id=\"blueimp-gallery\" class=\"blueimp-gallery blueimp-gallery-controls\">\n\t\t\t\t<div class=\"slides\"><\/div>\n\t\t\t\t<h3 class=\"title\"><\/h3>\n\t\t\t\t<a class=\"prev\">\u2039<\/a>\n\t\t\t\t<a class=\"next\">\u203a<\/a>\n\t\t\t\t<a class=\"close\">\u00d7<\/a>\n\t\t\t\t<a class=\"play-pause\"><\/a>\n\t\t\t\t<ol class=\"indicator\"><\/ol>\n\t\t\t\t<div class=\"modal fade\">\n\t\t\t\t\t<div class=\"modal-dialog\">\n\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" aria-hidden=\"true\">&times;<\/button>\n\t\t\t\t\t\t\t\t<h4 class=\"modal-title\"><\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"modal-body next\"><\/div>\n\t\t\t\t\t\t\t<div class=\"modal-footer\">\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn btn-default pull-left prev\">\n\t\t\t\t\t\t\t\t\t<i class=\"glyphicon glyphicon-chevron-left\"><\/i>\n\t\t\t\t\t\t\t\t\tPrevious\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button type=\"button\" class=\"btn btn-primary next\">\n\t\t\t\t\t\t\t\t\tNext\t\t\t\t\t\t\t\t\t<i class=\"glyphicon glyphicon-chevron-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<script type=\"text\/javascript\">\n\t\t\tjQuery(function() {\n\t\t\t\t\/\/ Set blueimp gallery options\n\t\t\t\tjQuery.extend(blueimp.Gallery.prototype.options, {\n\t\t\t\t\tuseBootstrapModal: false,\n\t\t\t\t\thidePageScrollbars: false\n\t\t\t\t});\n\t\t\t});\n\t\t\t<\/script>\n\t\t\t\n<p>VII Arte Ef\u00edmero e una gran oportunidad para dar a conocer nuestro pueblo a millones de lugares de todo el mundo&#8230; y ver que en otros lugares se hacen alfombras de flores, lentejas, garbanzos etc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VII Arte Ef\u00edmero e una gran oportunidad para dar a conocer nuestro pueblo a millones de lugares de todo el mundo&#8230; y ver que en&hellip; <\/p>\n","protected":false},"author":2,"featured_media":1038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[27,7,120,16],"tags":[231],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"http:\/\/mariajosesotos.es\/wp-content\/uploads\/2018\/07\/41498133280_a2f526e882_k.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p89WIH-gJ","_links":{"self":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/1037"}],"collection":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":1,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/1037\/revisions"}],"predecessor-version":[{"id":1039,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/posts\/1037\/revisions\/1039"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/media\/1038"}],"wp:attachment":[{"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/media?parent=1037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/categories?post=1037"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/mariajosesotos.es\/index.php\/wp-json\/wp\/v2\/tags?post=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}